{"id":2646,"date":"2023-01-23T14:59:29","date_gmt":"2023-01-23T13:59:29","guid":{"rendered":"https:\/\/trip-a-velo.com\/?post_type=docs&#038;p=2646"},"modified":"2023-12-07T14:37:20","modified_gmt":"2023-12-07T13:37:20","password":"","slug":"what-types-of-bikes-and-accessories-do-you-offer","status":"publish","type":"docs","link":"https:\/\/trip-a-velo.com\/en\/frequently-asked-questions\/what-types-of-bikes-and-accessories-do-you-offer\/","title":{"rendered":"What type of bikes and accessories do you offer?"},"content":{"rendered":"<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1685523078790\"><strong class=\"schema-faq-question\">What type of bikes and accessories do you offer?<\/strong> <p class=\"schema-faq-answer\">We offer VTC (all-road bikes) for men, women and children of all ages (16-20-24 inches) as well as electric bikes.<br\/>Please note: The law prohibits the use of electric bicycles by children under 14 years of age. An electric bike can propel up to 25 km\/hour, and in our opinion requires a certain maturity (time to adapt, ability to manage speeds and awareness of responsibilities).<br\/><br\/>For the youngest, we offer:<br\/><br\/>\u2013 The follower bike: without a front wheel, it attaches to the adult bike using a traction bar. Please note that the child will not be able to cycle alone.<br\/><br\/>\u2013 VTC 16 inches and more.<br\/><br\/>\u2013 The follow-me system allows children aged 5 to 8 or measuring between 1m10 and 1m35 to be connected to the adult bike or to pedal freely and whenever they want.<br\/><br\/>Helmet, anti-theft device, rear bag, front bag, luggage trailer, smartphone holder\u2026 you will find on each stay sheet the accessories included in our packages and the optional accessories.<\/p> <\/div> <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_mo_disable_npp":"","footnotes":""},"doc_category":[76],"doc_tag":[],"class_list":["post-2646","docs","type-docs","status-publish","hentry","doc_category-le-velo-et-ses-accessoires"],"year_month":"2026-09","word_count":188,"total_views":"7","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"FD communication","author_nicename":"fd-communication","author_url":"https:\/\/trip-a-velo.com\/en\/blog-voyage-a-velo\/author\/fd-communication\/"},"doc_category_info":[{"term_name":"Le v\u00e9lo et ses accessoires","term_url":"https:\/\/trip-a-velo.com\/en\/frequently-asked-questions-c\/the-bike-and-its-accessories\/"}],"doc_tag_info":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quels types de v\u00e9los et accessoires proposez-vous ? - FAQ - Trip \u00e0 v\u00e9lo<\/title>\n<meta name=\"description\" content=\"Nous proposons des VTC (v\u00e9lo tout chemin ) hommes, femmes et enfants de tous \u00e2ges (16-20-24 pouces) ainsi que des VAE (v\u00e9lo \u00e0 assistance...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trip-a-velo.com\/en\/frequently-asked-questions\/what-types-of-bikes-and-accessories-do-you-offer\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quels types de v\u00e9los et accessoires proposez-vous ? - FAQ - Trip \u00e0 v\u00e9lo\" \/>\n<meta property=\"og:description\" content=\"Nous proposons des VTC (v\u00e9lo tout chemin ) hommes, femmes et enfants de tous \u00e2ges (16-20-24 pouces) ainsi que des VAE (v\u00e9lo \u00e0 assistance...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trip-a-velo.com\/en\/frequently-asked-questions\/what-types-of-bikes-and-accessories-do-you-offer\/\" \/>\n<meta property=\"og:site_name\" content=\"Trip \u00e0 v\u00e9lo\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-07T13:37:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trip-a-velo.com\/wp-content\/uploads\/2023\/02\/sejours-a-velo-dans-le-val-de-loire-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"QAPage\",\"FAQPage\"],\"@id\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/frequently-asked-questions\\\/what-types-of-bikes-and-accessories-do-you-offer\\\/\",\"url\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/frequently-asked-questions\\\/what-types-of-bikes-and-accessories-do-you-offer\\\/\",\"name\":\"Quels types de v\u00e9los et accessoires proposez-vous ? - FAQ - Trip \u00e0 v\u00e9lo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/#website\"},\"datePublished\":\"2023-01-23T13:59:29+00:00\",\"dateModified\":\"2023-12-07T13:37:20+00:00\",\"description\":\"Nous proposons des VTC (v\u00e9lo tout chemin ) hommes, femmes et enfants de tous \u00e2ges (16-20-24 pouces) ainsi que des VAE (v\u00e9lo \u00e0 assistance...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/frequently-asked-questions\\\/what-types-of-bikes-and-accessories-do-you-offer\\\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/frequently-asked-questions\\\/what-types-of-bikes-and-accessories-do-you-offer\\\/#faq-question-1685523078790\"}],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/frequently-asked-questions\\\/what-types-of-bikes-and-accessories-do-you-offer\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/frequently-asked-questions\\\/what-types-of-bikes-and-accessories-do-you-offer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/trip-a-velo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Foire aux questions\",\"item\":\"https:\\\/\\\/trip-a-velo.com\\\/foire-aux-questions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le v\u00e9lo et ses accessoires\",\"item\":\"https:\\\/\\\/trip-a-velo.com\\\/foire-aux-questions-c\\\/le-velo-et-ses-accessoires\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Quels types de v\u00e9los et accessoires proposez-vous ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/\",\"name\":\"Trip \u00e0 v\u00e9lo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/#organization\",\"name\":\"Trip \u00e0 v\u00e9lo\",\"url\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/trip-a-velo.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-trip-a-velo-full.svg\",\"contentUrl\":\"https:\\\/\\\/trip-a-velo.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-trip-a-velo-full.svg\",\"width\":350,\"height\":201,\"caption\":\"Trip \u00e0 v\u00e9lo\"},\"image\":{\"@id\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/tripavelo\\\/\"]},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/frequently-asked-questions\\\/what-types-of-bikes-and-accessories-do-you-offer\\\/#faq-question-1685523078790\",\"position\":1,\"url\":\"https:\\\/\\\/trip-a-velo.com\\\/en\\\/frequently-asked-questions\\\/what-types-of-bikes-and-accessories-do-you-offer\\\/#faq-question-1685523078790\",\"name\":\"Quels types de v\u00e9los et accessoires proposez-vous ?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Nous proposons des VTC (v\u00e9lo tout chemin ) hommes, femmes et enfants de tous \u00e2ges (16-20-24 pouces) ainsi que des v\u00e9los \u00e9lectriques.<br\\\/>\u00c0 savoir : La loi interdit la pratique du v\u00e9lo \u00e9lectrique aux moins de 14 ans. Un v\u00e9lo \u00e9lectrique peut propulser jusqu\u2019\u00e0 25 km\\\/heure, et n\u00e9cessite \u00e0 notre sens une certaine maturit\u00e9 (temps d\u2019adaptation, aptitude \u00e0 g\u00e9rer les vitesses et conscience des responsabilit\u00e9s).<br\\\/><br\\\/>Pour les plus jeunes, nous proposons :<br\\\/><br\\\/>- Le v\u00e9lo suiveur : sans roue avant il s\u2019att\u00e8le au v\u00e9lo adulte gr\u00e2ce \u00e0 une barre de traction. A noter que l\u2019enfant n\u2019aura pas la possibilit\u00e9 de p\u00e9daler seul.<br\\\/><br\\\/>- VTC 16 pouces et plus.<br\\\/><br\\\/>- Le syst\u00e8me follow-me permet aux enfants de 5 \u00e0 8 ans ou mesurant entre 1m10 et 1m35 d\u2019\u00eatre reli\u00e9s au v\u00e9lo adulte ou de p\u00e9daler en toute libert\u00e9 et quand ils le souhaitent.<br\\\/><br\\\/>Casque, antivol, sacoche arri\u00e8re, sacoche avant, remorque bagages, support smartphone\u2026 vous trouverez sur chaque fiche de s\u00e9jour les accessoires inclus dans nos forfaits et les accessoires optionnels.\",\"inLanguage\":\"en-US\"},\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"What types of bikes and accessories do you offer? - FAQ - Trip \u00e0 v\u00e9lo","description":"We offer VTC (all-road bikes) for men, women and children of all ages (16-20-24 inches) as well as VAEs (assisted bikes...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trip-a-velo.com\/en\/frequently-asked-questions\/what-types-of-bikes-and-accessories-do-you-offer\/","og_locale":"en_US","og_type":"article","og_title":"Quels types de v\u00e9los et accessoires proposez-vous ? - FAQ - Trip \u00e0 v\u00e9lo","og_description":"Nous proposons des VTC (v\u00e9lo tout chemin ) hommes, femmes et enfants de tous \u00e2ges (16-20-24 pouces) ainsi que des VAE (v\u00e9lo \u00e0 assistance...","og_url":"https:\/\/trip-a-velo.com\/en\/frequently-asked-questions\/what-types-of-bikes-and-accessories-do-you-offer\/","og_site_name":"Trip \u00e0 v\u00e9lo","article_modified_time":"2023-12-07T13:37:20+00:00","og_image":[{"width":1366,"height":768,"url":"https:\/\/trip-a-velo.com\/wp-content\/uploads\/2023\/02\/sejours-a-velo-dans-le-val-de-loire-1.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","QAPage","FAQPage"],"@id":"https:\/\/trip-a-velo.com\/en\/frequently-asked-questions\/what-types-of-bikes-and-accessories-do-you-offer\/","url":"https:\/\/trip-a-velo.com\/en\/frequently-asked-questions\/what-types-of-bikes-and-accessories-do-you-offer\/","name":"What types of bikes and accessories do you offer? - FAQ - Trip \u00e0 v\u00e9lo","isPartOf":{"@id":"https:\/\/trip-a-velo.com\/en\/#website"},"datePublished":"2023-01-23T13:59:29+00:00","dateModified":"2023-12-07T13:37:20+00:00","description":"We offer VTC (all-road bikes) for men, women and children of all ages (16-20-24 inches) as well as VAEs (assisted bikes...","breadcrumb":{"@id":"https:\/\/trip-a-velo.com\/en\/frequently-asked-questions\/what-types-of-bikes-and-accessories-do-you-offer\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/trip-a-velo.com\/en\/frequently-asked-questions\/what-types-of-bikes-and-accessories-do-you-offer\/#faq-question-1685523078790"}],"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trip-a-velo.com\/en\/frequently-asked-questions\/what-types-of-bikes-and-accessories-do-you-offer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/trip-a-velo.com\/en\/frequently-asked-questions\/what-types-of-bikes-and-accessories-do-you-offer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/trip-a-velo.com\/"},{"@type":"ListItem","position":2,"name":"Foire aux questions","item":"https:\/\/trip-a-velo.com\/foire-aux-questions\/"},{"@type":"ListItem","position":3,"name":"Le v\u00e9lo et ses accessoires","item":"https:\/\/trip-a-velo.com\/foire-aux-questions-c\/le-velo-et-ses-accessoires\/"},{"@type":"ListItem","position":4,"name":"Quels types de v\u00e9los et accessoires proposez-vous ?"}]},{"@type":"WebSite","@id":"https:\/\/trip-a-velo.com\/en\/#website","url":"https:\/\/trip-a-velo.com\/en\/","name":"Trip \u00e0 v\u00e9lo","description":"","publisher":{"@id":"https:\/\/trip-a-velo.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trip-a-velo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/trip-a-velo.com\/en\/#organization","name":"Trip \u00e0 v\u00e9lo","url":"https:\/\/trip-a-velo.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/trip-a-velo.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/trip-a-velo.com\/wp-content\/uploads\/2022\/12\/logo-trip-a-velo-full.svg","contentUrl":"https:\/\/trip-a-velo.com\/wp-content\/uploads\/2022\/12\/logo-trip-a-velo-full.svg","width":350,"height":201,"caption":"Trip \u00e0 v\u00e9lo"},"image":{"@id":"https:\/\/trip-a-velo.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/tripavelo\/"]},{"@type":"Question","@id":"https:\/\/trip-a-velo.com\/en\/frequently-asked-questions\/what-types-of-bikes-and-accessories-do-you-offer\/#faq-question-1685523078790","position":1,"url":"https:\/\/trip-a-velo.com\/en\/frequently-asked-questions\/what-types-of-bikes-and-accessories-do-you-offer\/#faq-question-1685523078790","name":"What type of bikes and accessories do you offer?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Nous proposons des VTC (v\u00e9lo tout chemin ) hommes, femmes et enfants de tous \u00e2ges (16-20-24 pouces) ainsi que des v\u00e9los \u00e9lectriques.<br\/>\u00c0 savoir : La loi interdit la pratique du v\u00e9lo \u00e9lectrique aux moins de 14 ans. Un v\u00e9lo \u00e9lectrique peut propulser jusqu\u2019\u00e0 25 km\/heure, et n\u00e9cessite \u00e0 notre sens une certaine maturit\u00e9 (temps d\u2019adaptation, aptitude \u00e0 g\u00e9rer les vitesses et conscience des responsabilit\u00e9s).<br\/><br\/>Pour les plus jeunes, nous proposons :<br\/><br\/>- Le v\u00e9lo suiveur : sans roue avant il s\u2019att\u00e8le au v\u00e9lo adulte gr\u00e2ce \u00e0 une barre de traction. A noter que l\u2019enfant n\u2019aura pas la possibilit\u00e9 de p\u00e9daler seul.<br\/><br\/>- VTC 16 pouces et plus.<br\/><br\/>- Le syst\u00e8me follow-me permet aux enfants de 5 \u00e0 8 ans ou mesurant entre 1m10 et 1m35 d\u2019\u00eatre reli\u00e9s au v\u00e9lo adulte ou de p\u00e9daler en toute libert\u00e9 et quand ils le souhaitent.<br\/><br\/>Casque, antivol, sacoche arri\u00e8re, sacoche avant, remorque bagages, support smartphone\u2026 vous trouverez sur chaque fiche de s\u00e9jour les accessoires inclus dans nos forfaits et les accessoires optionnels.","inLanguage":"en-US"},"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/trip-a-velo.com\/en\/wp-json\/wp\/v2\/docs\/2646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trip-a-velo.com\/en\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/trip-a-velo.com\/en\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/trip-a-velo.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trip-a-velo.com\/en\/wp-json\/wp\/v2\/comments?post=2646"}],"version-history":[{"count":0,"href":"https:\/\/trip-a-velo.com\/en\/wp-json\/wp\/v2\/docs\/2646\/revisions"}],"wp:attachment":[{"href":"https:\/\/trip-a-velo.com\/en\/wp-json\/wp\/v2\/media?parent=2646"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/trip-a-velo.com\/en\/wp-json\/wp\/v2\/doc_category?post=2646"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/trip-a-velo.com\/en\/wp-json\/wp\/v2\/doc_tag?post=2646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}